{"id":983,"date":"2015-07-16T12:52:56","date_gmt":"2015-07-16T11:52:56","guid":{"rendered":"http:\/\/tugesto.com\/blog\/?p=983"},"modified":"2024-05-22T08:59:50","modified_gmt":"2024-05-22T06:59:50","slug":"ley-proteccion-datos-europea","status":"publish","type":"post","link":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/","title":{"rendered":"Ley de Protecci\u00f3n de Datos de la UE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"983\" class=\"elementor elementor-983\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62e034b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62e034b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35ccc72e\" data-id=\"35ccc72e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-668d49f6 elementor-widget elementor-widget-text-editor\" data-id=\"668d49f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">Tres a\u00f1os de debate han llevado a la Uni\u00f3n Europea a cerrar un acuerdo sobre la Ley de Protecci\u00f3n de datos que <strong>unifica las leyes que proteger\u00e1n los datos de todos los ciudadanos europeos<\/strong>. De esa manera, en junio, se aprob\u00f3 una ley sobre la LOPD que supone el cumplimiento por parte de los 28 pa\u00edses miembro de una normativa com\u00fan.<\/p><p style=\"text-align: justify;\">El anterior reglamento, que databa de 1995, se ha sustituido tras 20 a\u00f1os de avances tecnol\u00f3gicos imparables. De esa manera, <strong>el Parlamento Europeo ha aprobado un acuerdo que toma como modelo las leyes que rigen la AEPD (Agencia Espa\u00f1ola de Protecci\u00f3n de Datos)<\/strong>.<\/p><p><a href=\"http:\/\/www.tugesto.com\/software-lopd\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-20888 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/Delegado-proteccion-datos-solicita-informacion.png\" alt=\"\" width=\"800\" height=\"241\" srcset=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/Delegado-proteccion-datos-solicita-informacion.png 800w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/Delegado-proteccion-datos-solicita-informacion-300x90.png 300w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/Delegado-proteccion-datos-solicita-informacion-768x231.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p><h2 style=\"text-align: justify;\">\u00bfQu\u00e9 recoge esta normativa?<\/h2><p style=\"text-align: justify;\">La legislaci\u00f3n europea sobre la ley de protecci\u00f3n de datos pretende que se cumpla una normativa en un conjunto \u00fanico que garantice que los ciudadanos europeos tengan la misma protecci\u00f3n de sus datos en los tribunales estadounidenses que la que tenemos en la Uni\u00f3n Europea, al igual que ocurre a la inversa, adem\u00e1s de evitar normativas mucho m\u00e1s flexibles que existen en pa\u00edses como Irlanda. De esa manera, con este acuerdo, se ha llegado a una modernizaci\u00f3n de la LOPD y se proteger\u00e1 con mayor contundencia la privacidad de los europeos.<\/p><ol style=\"text-align: justify;\"><li>Promueve las <strong>mismas garant\u00edas en entornos digitales<\/strong> que en los entornos no digitales.<\/li><li>\u00a0Se recoge, por primera vez, de forma expresa <a title=\"El \u2018derecho al olvido\u2019 va ganando peque\u00f1as batallas\" href=\"https:\/\/tugesto.com\/blog\/el-derecho-al-olvido-va-ganando-pequenas-batallas\/\" target=\"_blank\" rel=\"noopener\"><strong>el derecho al olvido<\/strong><\/a>, que ya fue reconocido por el Tribunal de Justicia de la Uni\u00f3n Europea.<\/li><li><strong>Se elimina la posibilidad de presentar una demanda colectiva<\/strong> por la vulneraci\u00f3n de la protecci\u00f3n de datos.<\/li><li>La normativa <strong>no impedir\u00e1 publicar los datos de morosos<\/strong>.<\/li><li>La ley europea <strong>ser\u00e1 de aplicaci\u00f3n directa en los 28 pa\u00edses<\/strong>, anulando las leyes nacionales vigentes.<\/li><li>Permitir\u00e1 imponer <strong>multas a las compa\u00f1\u00edas de hasta un 2% de su volumen de negocio o un m\u00e1ximo de 1 mill\u00f3n de euros<\/strong>. La norma se aplicar\u00e1 a las empresas europeas y multinacionales presentes en el continente. Para las pymes tambi\u00e9n se recurrir\u00e1 a sanciones por no cumplir con la ley que pueden llegar hasta los 600.000 euros.<\/li><li>Se <strong>simplificar\u00e1 el cumplimiento mediante la eliminaci\u00f3n de requisitos administrativos innecesarios<\/strong>, como los que se piden para la notificaci\u00f3n de las empresas. En definitiva, se reducir\u00e1 la burocracia y se aumentar\u00e1 la seguridad jur\u00eddica de la empresa.<\/li><li>Todas las autoridades de protecci\u00f3n de datos tendr\u00e1n las <strong>mismas potestades de investigaci\u00f3n y de sanci\u00f3n<\/strong>.<\/li><li><strong>Las compa\u00f1\u00edas que act\u00faen en Europa<\/strong> tratando datos de europeos, aunque no tengan su sede en la UE, <strong>estar\u00e1n sujetas a la legislaci\u00f3n europea<\/strong>.<\/li><\/ol><p style=\"text-align: justify;\">Desde el <a href=\"https:\/\/www.europarl.europa.eu\/portal\/es\" target=\"_blank\" rel=\"noopener\">Parlamento Europeo<\/a> se ha detallado, que aunque la protecci\u00f3n de datos empieza por uno mismo, las empresas, ya sea una peque\u00f1a o una multinacional tienen una gran responsabilidad y se les reclamar\u00e1 que sean transparentes con los usuarios, que se informe de forma clara de qu\u00e9 datos se est\u00e1n recopilando, qu\u00e9 usos se hacen de los datos y si los ceden a terceros, informar de a qui\u00e9n se los ceden.<\/p><p><a href=\"http:\/\/tugesto.com\/software-lopd\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-7865 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2017\/12\/LOPD.gif\" alt=\"Servicio de protecci\u00f3n de datos\" width=\"1000\" height=\"600\" \/><\/a><\/p><p style=\"text-align: justify;\">Las empresas deben estar preparadas, hasta ahora, en Espa\u00f1a ya se impon\u00edan grandes <a title=\"\u00bfQu\u00e9 sanciones me afectan como empresa si no cumplo con la LOPD?\" href=\"https:\/\/tugesto.com\/blog\/sanciones-nocumplir-lopd\/\" target=\"_blank\" rel=\"noopener\">sanciones por el incumpliendo de la LOPD<\/a> a trav\u00e9s de la AEPD, a partir de ahora, las nuevas leyes europeas ser\u00e1n las que rijan nuestra protecci\u00f3n de datos. Si eres una pyme, o incluso, un aut\u00f3nomo que maneja datos de clientes est\u00e1 normativa te afecta de forma trascendental.<\/p><h2 style=\"text-align: justify;\">\u00a1Hazte con el software LOPD de tugesto y despreoc\u00fapate!<\/h2><p style=\"text-align: justify;\">No lo dudes, en tugesto contamos con un <a href=\"http:\/\/www.tugesto.com\/software-lopd\" target=\"_blank\" rel=\"noopener\">software LOPD<\/a>, una <strong>herramienta online que con un s\u00f3lo modulo destinado a la seguridad, cumplimiento y adaptaci\u00f3n de las empresas a la LOPD<\/strong> te ayudar\u00e1 a estar tranquilo y gestionar el tratamiento de datos para cumplir tus obligaciones con la nueva normativa europea.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tres a\u00f1os de debate han llevado a la Uni\u00f3n Europea a cerrar un acuerdo sobre la Ley de Protecci\u00f3n de datos que unifica las leyes que proteger\u00e1n los datos de todos los ciudadanos europeos. De esa manera, en junio, se aprob\u00f3 una ley sobre la LOPD que supone el cumplimiento por parte de los 28 [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_eb_attr":"","content-type":"","footnotes":""},"categories":[51],"tags":[36,38],"ppma_author":[1501],"class_list":["post-983","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-proteccion-de-datos","tag-autonomos","tag-pymes","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ley de Protecci\u00f3n de Datos de la UE | tugesto<\/title>\n<meta name=\"description\" content=\"Tres a\u00f1os de debate han llevado a la Uni\u00f3n Europea a cerrar un acuerdo sobre la Ley de Protecci\u00f3n de datos que unifica todas estas leyes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ley de Protecci\u00f3n de Datos de la UE | tugesto\" \/>\n<meta property=\"og:description\" content=\"Tres a\u00f1os de debate han llevado a la Uni\u00f3n Europea a cerrar un acuerdo sobre la Ley de Protecci\u00f3n de datos que unifica todas estas leyes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog: \u00a1Aprende a emprender! | tugesto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tugesto\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-16T11:52:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-22T06:59:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/07\/ley-proteccion-datos-europea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosa Gonz\u00e1lez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosa Gonz\u00e1lez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/\"},\"author\":{\"name\":\"Rosa Gonz\u00e1lez\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/person\\\/ac35495ec7b2332a9618c7898ca70db2\"},\"headline\":\"Ley de Protecci\u00f3n de Datos de la UE\",\"datePublished\":\"2015-07-16T11:52:56+00:00\",\"dateModified\":\"2024-05-22T06:59:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/\"},\"wordCount\":661,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/ley-proteccion-datos-europea.jpg\",\"keywords\":[\"aut\u00f3nomos\",\"pymes\"],\"articleSection\":[\"Protecci\u00f3n de datos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/\",\"name\":\"Ley de Protecci\u00f3n de Datos de la UE | tugesto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/ley-proteccion-datos-europea.jpg\",\"datePublished\":\"2015-07-16T11:52:56+00:00\",\"dateModified\":\"2024-05-22T06:59:50+00:00\",\"description\":\"Tres a\u00f1os de debate han llevado a la Uni\u00f3n Europea a cerrar un acuerdo sobre la Ley de Protecci\u00f3n de datos que unifica todas estas leyes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/ley-proteccion-datos-europea.jpg\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/ley-proteccion-datos-europea.jpg\",\"width\":700,\"height\":329,\"caption\":\"Despu\u00e9s de mucho tiempo, es momento de recoger todos los datos sobre la LOPD en el entorno europeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/ley-proteccion-datos-europea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protecci\u00f3n de datos\",\"item\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/category\\\/proteccion-de-datos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ley de Protecci\u00f3n de Datos de la UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\",\"name\":\"Blog tugesto\",\"description\":\"\ud83d\udcda Blog especializado para aut\u00f3nomos y pymes. Encuentra semanalmente nuevos posts, recursos y gu\u00edas. La ayuda que necesitas para tu negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\",\"name\":\"tugesto\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo_tugesto.png\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo_tugesto.png\",\"width\":190,\"height\":63,\"caption\":\"tugesto\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tugesto\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tugesto_online\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/person\\\/ac35495ec7b2332a9618c7898ca70db2\",\"name\":\"Rosa Gonz\u00e1lez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/rosa-gonzalez.png0ece644c332d38b899bac1149cf9912a\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/rosa-gonzalez.png\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/rosa-gonzalez.png\",\"caption\":\"Rosa Gonz\u00e1lez\"},\"description\":\"Abogada, departamento jur\u00eddico-legal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ley de Protecci\u00f3n de Datos de la UE | tugesto","description":"Tres a\u00f1os de debate han llevado a la Uni\u00f3n Europea a cerrar un acuerdo sobre la Ley de Protecci\u00f3n de datos que unifica todas estas leyes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/","og_locale":"es_ES","og_type":"article","og_title":"Ley de Protecci\u00f3n de Datos de la UE | tugesto","og_description":"Tres a\u00f1os de debate han llevado a la Uni\u00f3n Europea a cerrar un acuerdo sobre la Ley de Protecci\u00f3n de datos que unifica todas estas leyes","og_url":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/","og_site_name":"Blog: \u00a1Aprende a emprender! | tugesto","article_publisher":"https:\/\/www.facebook.com\/tugesto\/","article_published_time":"2015-07-16T11:52:56+00:00","article_modified_time":"2024-05-22T06:59:50+00:00","og_image":[{"width":700,"height":329,"url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/07\/ley-proteccion-datos-europea.jpg","type":"image\/jpeg"}],"author":"Rosa Gonz\u00e1lez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rosa Gonz\u00e1lez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/#article","isPartOf":{"@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/"},"author":{"name":"Rosa Gonz\u00e1lez","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/person\/ac35495ec7b2332a9618c7898ca70db2"},"headline":"Ley de Protecci\u00f3n de Datos de la UE","datePublished":"2015-07-16T11:52:56+00:00","dateModified":"2024-05-22T06:59:50+00:00","mainEntityOfPage":{"@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/"},"wordCount":661,"commentCount":2,"publisher":{"@id":"https:\/\/tugesto.com\/blog\/#organization"},"image":{"@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/07\/ley-proteccion-datos-europea.jpg","keywords":["aut\u00f3nomos","pymes"],"articleSection":["Protecci\u00f3n de datos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/","url":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/","name":"Ley de Protecci\u00f3n de Datos de la UE | tugesto","isPartOf":{"@id":"https:\/\/tugesto.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/#primaryimage"},"image":{"@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/07\/ley-proteccion-datos-europea.jpg","datePublished":"2015-07-16T11:52:56+00:00","dateModified":"2024-05-22T06:59:50+00:00","description":"Tres a\u00f1os de debate han llevado a la Uni\u00f3n Europea a cerrar un acuerdo sobre la Ley de Protecci\u00f3n de datos que unifica todas estas leyes","breadcrumb":{"@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/#primaryimage","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/07\/ley-proteccion-datos-europea.jpg","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/07\/ley-proteccion-datos-europea.jpg","width":700,"height":329,"caption":"Despu\u00e9s de mucho tiempo, es momento de recoger todos los datos sobre la LOPD en el entorno europeo"},{"@type":"BreadcrumbList","@id":"https:\/\/tugesto.com\/blog\/ley-proteccion-datos-europea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tugesto.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Protecci\u00f3n de datos","item":"https:\/\/tugesto.com\/blog\/category\/proteccion-de-datos\/"},{"@type":"ListItem","position":3,"name":"Ley de Protecci\u00f3n de Datos de la UE"}]},{"@type":"WebSite","@id":"https:\/\/tugesto.com\/blog\/#website","url":"https:\/\/tugesto.com\/blog\/","name":"Blog tugesto","description":"\ud83d\udcda Blog especializado para aut\u00f3nomos y pymes. Encuentra semanalmente nuevos posts, recursos y gu\u00edas. La ayuda que necesitas para tu negocio.","publisher":{"@id":"https:\/\/tugesto.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tugesto.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tugesto.com\/blog\/#organization","name":"tugesto","url":"https:\/\/tugesto.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2019\/06\/logo_tugesto.png","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2019\/06\/logo_tugesto.png","width":190,"height":63,"caption":"tugesto"},"image":{"@id":"https:\/\/tugesto.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tugesto\/","https:\/\/www.instagram.com\/tugesto_online\/"]},{"@type":"Person","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/person\/ac35495ec7b2332a9618c7898ca70db2","name":"Rosa Gonz\u00e1lez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/rosa-gonzalez.png0ece644c332d38b899bac1149cf9912a","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/rosa-gonzalez.png","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/rosa-gonzalez.png","caption":"Rosa Gonz\u00e1lez"},"description":"Abogada, departamento jur\u00eddico-legal"}]}},"authors":[{"term_id":1501,"user_id":15,"is_guest":0,"slug":"rosa-gonzalez","display_name":"Rosa Gonz\u00e1lez","avatar_url":{"url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/rosa-gonzalez.png","url2x":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/rosa-gonzalez.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/comments?post=983"}],"version-history":[{"count":14,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/983\/revisions"}],"predecessor-version":[{"id":35912,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/983\/revisions\/35912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/media\/986"}],"wp:attachment":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/media?parent=983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/categories?post=983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/tags?post=983"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/ppma_author?post=983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}