{"id":8775,"date":"2018-10-19T08:00:05","date_gmt":"2018-10-19T07:00:05","guid":{"rendered":"https:\/\/tugesto.com\/blog\/?p=8775"},"modified":"2024-05-20T08:22:54","modified_gmt":"2024-05-20T06:22:54","slug":"lo-debes-saber-acerca-del-codigo-cnae","status":"publish","type":"post","link":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/","title":{"rendered":"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8775\" class=\"elementor elementor-8775\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ad1048d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ad1048d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-451fc22a\" data-id=\"451fc22a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61c3e15e elementor-widget elementor-widget-text-editor\" data-id=\"61c3e15e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #4c4f54;\">\u00bfTe suena de algo qu\u00e9 es el c\u00f3digo CNAE y no sabes con exactitud de qu\u00e9 se trata? <strong>Si ejerces una actividad econ\u00f3mica este post te interesa<\/strong>.<\/span><\/p><h2><span style=\"color: #4c4f54;\">\u00bfQu\u00e9 es el c\u00f3digo CNAE?<\/span><\/h2><p><span style=\"color: #4c4f54;\">CNAE son las siglas de <strong>Clasificaci\u00f3n Nacional de Actividades Econ\u00f3micas<\/strong>. Este c\u00f3digo no es m\u00e1s que un sistema num\u00e9rico para organizar y agrupar las unidades productoras seg\u00fan su principal actividad econ\u00f3mica. A cada unidad productiva se le asigna un c\u00f3digo num\u00e9rico para poder ordenar el grupo de actividades econ\u00f3micas. Es por eso, que su finalidad es realizar seguimientos de las actividades de los agentes econ\u00f3micos para la realizaci\u00f3n de informes y estudios.<\/span><\/p><p><a href=\"http:\/\/tugesto.com\/software-fiscal\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-14766 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/gestionar_fiscalidad_online.jpg\" alt=\"Gestiona tu fiscalidad online con respaldo de asesores expertos\" width=\"798\" height=\"241\" srcset=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/gestionar_fiscalidad_online.jpg 798w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/gestionar_fiscalidad_online-300x91.jpg 300w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/gestionar_fiscalidad_online-768x232.jpg 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/a><\/p><p><span style=\"color: #4c4f54;\">Asimismo, el c\u00f3digo CNAE <strong>favorece la implementaci\u00f3n de estad\u00edsticas nacionales que puedan ser diferenciadas y la clasificaci\u00f3n de unidades estad\u00edsticas y entidades seg\u00fan la actividad econ\u00f3mica<\/strong>.<\/span><br \/><span style=\"color: #4c4f54;\">Toda sociedad que ejerza una actividad econ\u00f3mica debe reflejar el c\u00f3digo CNAE en sus escrituras de constituci\u00f3n, en los acuerdos sociales y en las cuentas peri\u00f3dicas de los registros p\u00fablicos.<\/span><\/p><h2><span style=\"color: #4c4f54;\">\u00bfCu\u00e1les son los grupos CNAE?<\/span><\/h2><p><a href=\"http:\/\/www.codigoscnae.es\/todosloscodigoscnae\" target=\"_blank\" rel=\"noopener\">Hay 20 grupos y est\u00e1n clasificados seg\u00fan su actividad econ\u00f3mica.<\/a> <span style=\"color: #4c4f54;\">Ten en cuenta que cada grupo o letra alberga subgrupos de todas las unidades productoras. Es decir, en el grupo B (Industrias extractivas) se incluye la extracci\u00f3n de crudo y petr\u00f3leo (n\u00ba061). Si te dedicas a esta extracci\u00f3n tu c\u00f3digo ser\u00e1 el n\u00famero 061.<\/span><\/p><p><span style=\"color: #4c4f54;\">Los grupos son los siguientes:<\/span><\/p><ul><li><span style=\"color: #4c4f54;\"><strong>A: Agricultura, ganader\u00eda, silvicultura y pesca<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>B: Industrias extractivas<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>C: Industria manufacturera<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>D: Suministro de energ\u00eda el\u00e9ctrica, gas, vapor y aire acondicionado<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>E: Suministro de agua, actividades de saneamiento, gesti\u00f3n de residuos y descontaminaci\u00f3n<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>F: Construcci\u00f3n<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>G: Comercio al por mayor y el por menor; reparaci\u00f3n de veh\u00edculos de motor y motocicletas<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>H: Transporte y almacenamiento<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>I: Hosteler\u00eda<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>J: Informaci\u00f3n y comunicaci\u00f3n<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>K: Actividades financieras y seguros<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>L: Actividades inmobiliarias<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>M: Actividades profesionales, cient\u00edficas y t\u00e9cnicas<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>N: Actividades administrativas y servicios auxiliares<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>O: Administraci\u00f3n P\u00fablica y defensa; Seguridad Social obligatoria<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>P: Educaci\u00f3n<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>R: Actividades art\u00edsticas, recreativas y de entretenimiento<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>S: Otros servicios<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>T: Actividades de los hogares como empleadores del personal dom\u00e9stico<\/strong><\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>U: Actividades de organizaci\u00f3n y organismos extraterritoriales<\/strong><\/span><\/li><\/ul><p><span style=\"color: #4c4f54;\">Importante: Si la actividad econ\u00f3mica cambia, es interesante notificarlo, proceder a obtener un nuevo c\u00f3digo CNAE y registrarlo en el Registro Mercantil.<\/span><\/p><h2><span style=\"color: #4c4f54;\">\u00bfEs lo mismo el c\u00f3digo CNAE que el ep\u00edgrafe IAE?<\/span><\/h2><p><span style=\"color: #4c4f54;\">En absoluto. Mientras que el <strong>IAE es un impuesto y marca la forma en la que tributas, el CNAE es una clasificaci\u00f3n para organizar un listado de unidades productoras<\/strong>. El c\u00f3digo CNAE tiene valor estad\u00edstico y se origina en el<\/span> <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/ES\/ALL\/?uri=celex:32011R1169\" target=\"_blank\" rel=\"noopener\">Reglamento Comunitario.<\/a><\/p><p><span style=\"color: #4c4f54;\">Si deseas asesoramiento sobre el c\u00f3digo CNAE que debes obtener o sobre otra cuesti\u00f3n, tenemos un equipo de asesores contables y laborales a tu disposici\u00f3n. M\u00e1ndanos un correo a<\/span> <a href=\"mailto:info@tugesto.com\" target=\"_blank\" rel=\"noopener\">info@tugesto.com<\/a> <span style=\"color: #4c4f54;\">o llama al 902 105 062.<\/span><\/p><p><a href=\"https:\/\/tugesto.com\/alta-autonomo\/?utm_source=blog&amp;utm_medium=banner&amp;utm_campaign=cnae\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/10\/contabilidad_fiscal-tarifas_tugesto.gif\" alt=\"Tarifa plana de contabilidad y fiscal\" width=\"1000\" height=\"600\" \/><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfTe suena de algo qu\u00e9 es el c\u00f3digo CNAE y no sabes con exactitud de qu\u00e9 se trata? Si ejerces una actividad econ\u00f3mica este post te interesa. \u00bfQu\u00e9 es el c\u00f3digo CNAE? CNAE son las siglas de Clasificaci\u00f3n Nacional de Actividades Econ\u00f3micas. Este c\u00f3digo no es m\u00e1s que un sistema num\u00e9rico para organizar y agrupar [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","content-type":"","footnotes":""},"categories":[14],"tags":[36,38],"ppma_author":[1494],"class_list":["post-8775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contabilidad-y-fiscal","tag-autonomos","tag-pymes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber | tugesto<\/title>\n<meta name=\"description\" content=\"\u00bfNo sabes qu\u00e9 es el c\u00f3digo CNAE o cu\u00e1les son sus grupos? Te contamos todo sobre este c\u00f3digo en nuestro post a continuaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber | tugesto\" \/>\n<meta property=\"og:description\" content=\"\u00bfNo sabes qu\u00e9 es el c\u00f3digo CNAE o cu\u00e1les son sus grupos? Te contamos todo sobre este c\u00f3digo en nuestro post a continuaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog: \u00a1Aprende a emprender! | tugesto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tugesto\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-19T07:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-20T06:22:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/10\/codigos_CNAE-asesores_digitales.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3125\" \/>\n\t<meta property=\"og:image:height\" content=\"1788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Esteban Escribano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esteban Escribano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/\"},\"author\":{\"name\":\"Esteban Escribano\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/person\\\/f210b25a9ff7b95404fdcd6d6e7d21e6\"},\"headline\":\"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber\",\"datePublished\":\"2018-10-19T07:00:05+00:00\",\"dateModified\":\"2024-05-20T06:22:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/\"},\"wordCount\":527,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/codigos_CNAE-asesores_digitales.png\",\"keywords\":[\"aut\u00f3nomos\",\"pymes\"],\"articleSection\":[\"Contabilidad y Fiscal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/\",\"name\":\"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber | tugesto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/codigos_CNAE-asesores_digitales.png\",\"datePublished\":\"2018-10-19T07:00:05+00:00\",\"dateModified\":\"2024-05-20T06:22:54+00:00\",\"description\":\"\u00bfNo sabes qu\u00e9 es el c\u00f3digo CNAE o cu\u00e1les son sus grupos? Te contamos todo sobre este c\u00f3digo en nuestro post a continuaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/codigos_CNAE-asesores_digitales.png\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/codigos_CNAE-asesores_digitales.png\",\"width\":3125,\"height\":1788,\"caption\":\"\u00bfEjerces una actividad econ\u00f3mica y no sabes del todo qu\u00e9 es el c\u00f3digo CNAE? Este post te interesa.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/lo-debes-saber-acerca-del-codigo-cnae\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contabilidad y Fiscal\",\"item\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/category\\\/contabilidad-y-fiscal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\",\"name\":\"Blog tugesto\",\"description\":\"\ud83d\udcda Blog especializado para aut\u00f3nomos y pymes. Encuentra semanalmente nuevos posts, recursos y gu\u00edas. La ayuda que necesitas para tu negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\",\"name\":\"tugesto\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo_tugesto.png\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo_tugesto.png\",\"width\":190,\"height\":63,\"caption\":\"tugesto\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tugesto\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tugesto_online\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/person\\\/f210b25a9ff7b95404fdcd6d6e7d21e6\",\"name\":\"Esteban Escribano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/esteban-escribano.png85c872baa50e8ebdd3625a327ee22292\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/esteban-escribano.png\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/esteban-escribano.png\",\"caption\":\"Esteban Escribano\"},\"description\":\"Responsable del departamento laboral\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber | tugesto","description":"\u00bfNo sabes qu\u00e9 es el c\u00f3digo CNAE o cu\u00e1les son sus grupos? Te contamos todo sobre este c\u00f3digo en nuestro post a continuaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber | tugesto","og_description":"\u00bfNo sabes qu\u00e9 es el c\u00f3digo CNAE o cu\u00e1les son sus grupos? Te contamos todo sobre este c\u00f3digo en nuestro post a continuaci\u00f3n","og_url":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/","og_site_name":"Blog: \u00a1Aprende a emprender! | tugesto","article_publisher":"https:\/\/www.facebook.com\/tugesto\/","article_published_time":"2018-10-19T07:00:05+00:00","article_modified_time":"2024-05-20T06:22:54+00:00","og_image":[{"width":3125,"height":1788,"url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/10\/codigos_CNAE-asesores_digitales.png","type":"image\/png"}],"author":"Esteban Escribano","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Esteban Escribano","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/#article","isPartOf":{"@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/"},"author":{"name":"Esteban Escribano","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/person\/f210b25a9ff7b95404fdcd6d6e7d21e6"},"headline":"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber","datePublished":"2018-10-19T07:00:05+00:00","dateModified":"2024-05-20T06:22:54+00:00","mainEntityOfPage":{"@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/"},"wordCount":527,"commentCount":0,"publisher":{"@id":"https:\/\/tugesto.com\/blog\/#organization"},"image":{"@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/#primaryimage"},"thumbnailUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/10\/codigos_CNAE-asesores_digitales.png","keywords":["aut\u00f3nomos","pymes"],"articleSection":["Contabilidad y Fiscal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/","url":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/","name":"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber | tugesto","isPartOf":{"@id":"https:\/\/tugesto.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/#primaryimage"},"image":{"@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/#primaryimage"},"thumbnailUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/10\/codigos_CNAE-asesores_digitales.png","datePublished":"2018-10-19T07:00:05+00:00","dateModified":"2024-05-20T06:22:54+00:00","description":"\u00bfNo sabes qu\u00e9 es el c\u00f3digo CNAE o cu\u00e1les son sus grupos? Te contamos todo sobre este c\u00f3digo en nuestro post a continuaci\u00f3n","breadcrumb":{"@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/#primaryimage","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/10\/codigos_CNAE-asesores_digitales.png","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/10\/codigos_CNAE-asesores_digitales.png","width":3125,"height":1788,"caption":"\u00bfEjerces una actividad econ\u00f3mica y no sabes del todo qu\u00e9 es el c\u00f3digo CNAE? Este post te interesa."},{"@type":"BreadcrumbList","@id":"https:\/\/tugesto.com\/blog\/lo-debes-saber-acerca-del-codigo-cnae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tugesto.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Contabilidad y Fiscal","item":"https:\/\/tugesto.com\/blog\/category\/contabilidad-y-fiscal\/"},{"@type":"ListItem","position":3,"name":"Qu\u00e9 es el c\u00f3digo CNAE: todo lo que necesitas saber"}]},{"@type":"WebSite","@id":"https:\/\/tugesto.com\/blog\/#website","url":"https:\/\/tugesto.com\/blog\/","name":"Blog tugesto","description":"\ud83d\udcda Blog especializado para aut\u00f3nomos y pymes. Encuentra semanalmente nuevos posts, recursos y gu\u00edas. La ayuda que necesitas para tu negocio.","publisher":{"@id":"https:\/\/tugesto.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tugesto.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tugesto.com\/blog\/#organization","name":"tugesto","url":"https:\/\/tugesto.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2019\/06\/logo_tugesto.png","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2019\/06\/logo_tugesto.png","width":190,"height":63,"caption":"tugesto"},"image":{"@id":"https:\/\/tugesto.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tugesto\/","https:\/\/www.instagram.com\/tugesto_online\/"]},{"@type":"Person","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/person\/f210b25a9ff7b95404fdcd6d6e7d21e6","name":"Esteban Escribano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/esteban-escribano.png85c872baa50e8ebdd3625a327ee22292","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/esteban-escribano.png","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/esteban-escribano.png","caption":"Esteban Escribano"},"description":"Responsable del departamento laboral"}]}},"authors":[{"term_id":1494,"user_id":8,"is_guest":0,"slug":"esteban-escribano","display_name":"Esteban Escribano","avatar_url":{"url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/esteban-escribano.png","url2x":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/esteban-escribano.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/8775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/comments?post=8775"}],"version-history":[{"count":8,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/8775\/revisions"}],"predecessor-version":[{"id":35520,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/8775\/revisions\/35520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/media\/8782"}],"wp:attachment":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/media?parent=8775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/categories?post=8775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/tags?post=8775"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/ppma_author?post=8775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}