{"id":2741,"date":"2016-04-05T12:59:25","date_gmt":"2016-04-05T11:59:25","guid":{"rendered":"http:\/\/tugesto.com\/blog\/?p=2741"},"modified":"2024-05-21T11:55:21","modified_gmt":"2024-05-21T09:55:21","slug":"evitar-suplantacion-de-identidad","status":"publish","type":"post","link":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/","title":{"rendered":"C\u00f3mo evitar la suplantaci\u00f3n de identidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2741\" class=\"elementor elementor-2741\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ed7f3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ed7f3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b12761a\" data-id=\"b12761a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fd59ef5 elementor-widget elementor-widget-text-editor\" data-id=\"1fd59ef5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">La <strong>protecci\u00f3n de los\u00a0datos personales<\/strong> cobra una\u00a0importancia especial en el mundo actual donde vivimos. La inevitable revoluci\u00f3n tecnol\u00f3gica ha modificado nuestro <em>modus vivendi<\/em>, manifestando un uso diario de Internet en diferentes dispositivos: m\u00f3vil, ordenador, tablet\u2026 Muy cerca del uso de la\u00a0tecnolog\u00eda se encuentra el sujeto que se aprovecha de la vulnerabilidad de la v\u00edctima, y es entonces, el momento justo donde se desarrolla la <strong>suplantaci\u00f3n de identidad digital y no digital<em>.<\/em><\/strong><\/span><\/p><p style=\"text-align: justify;\"><a href=\"http:\/\/tugesto.com\/software-lopd\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-7899 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/01\/LOPD.gif\" alt=\"Servicio de protecci\u00f3n de datos\" width=\"1000\" height=\"600\" \/><\/a><\/p><h2 style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">\u00bfQu\u00e9 es la identidad?<\/span><\/h2><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Todos los seres humanos estamos dotados de unos<strong> derechos y unas obligaciones<\/strong>, todo ello por el simple hecho de nacer dentro de un territorio nacional, dichos beneficios son <strong>otorgados por el Estado. <\/strong><\/span><\/p><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Es nuestra responsabilidad corresponder al beneficio procurando estar en verdadero control de nuestros datos personales.<\/span><\/p><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">La <strong>identidad<em>,<\/em><\/strong> en concreto, es un beneficio otorgado por el Estado.<\/span><\/p><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">\u00c9ste es el encargado de\u00a0generar documentos oficiales que acrediten nuestros <strong>datos personales<\/strong>.<\/span><\/p><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Por ello, cada uno de nosotros cuenta con documentaci\u00f3n que acredita nuestra nacionalidad, lugar y fecha de nacimiento y n\u00famero de control dentro de los registros estatales.<\/span><\/p><h2 style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">\u00bfQu\u00e9 es la suplantaci\u00f3n de identidad?<\/span><\/h2><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">La suplantaci\u00f3n de identidad es aquella acci\u00f3n por la que una persona se hace pasar por otra para llevar a cabo <strong>actividades de car\u00e1cter ilegal <\/strong>como por ejemplo<strong>\u00a0solicitar un cr\u00e9dito<\/strong> o un <strong>pr\u00e9stamo hipotecario<\/strong>, contratar nuevas l\u00edneas telef\u00f3nicas pas\u00e1ndote por otra persona o realizar ataques contra terceras personas.<\/span><\/p><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Se trata de una de las <strong>actividades il\u00edcitas<\/strong> que m\u00e1s ha incrementado en los \u00faltimos a\u00f1os. Son muchas las personas que se han visto inmersas como v\u00edctimas en situaciones as\u00ed.<\/span><\/p><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">De hecho, Yolanda Garc\u00eda, Coordinadora del Grado de Derecho y del M\u00e1ster Universitario en Abogac\u00eda y Pr\u00e1ctica Jur\u00eddica de la Universidad Internacional de Valencia (VIU), asegura que <em>\u00ablas denuncias por suplantaci\u00f3n de identidad se han incrementado en m\u00e1s de un 200% en el caso de sectores como el del suministro y comercializaci\u00f3n de energ\u00eda y agua y m\u00e1s de un 90% en el caso de las telecomunicaciones.\u00bb<\/em><\/span><\/p><p style=\"text-align: justify;\"><iframe src=\"https:\/\/www.youtube.com\/embed\/sKcY5uW57lw\" width=\"600\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p><h2 style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Motivos del incremento de delitos de suplantaci\u00f3n de identidad<\/span><\/h2><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Hoy en d\u00eda, la delincuencia busca diversas situaciones que pueden ser bien aprovechadas para cometer delitos o simplemente perjudicar a otra persona. Una muestra de ello, es la suplantaci\u00f3n de identidad, fen\u00f3meno que ha retomado fuerza por los siguientes motivos:<\/span><\/p><ol style=\"text-align: justify;\"><li style=\"list-style-type: none;\"><ol style=\"text-align: justify;\"><li style=\"text-align: justify;\"><span style=\"color: #4c4f54;\"><strong>Nuestra vulnerabilidad y exceso de confianza<\/strong>. Esto sucede cuando simplemente a trav\u00e9s de la telefon\u00eda aceptamos proporcionar cualquier informaci\u00f3n que nos solicitan, sin pensar que puede tratarse de un sujeto que utiliza dicha confidencialidad para obtener beneficios econ\u00f3micos o patrimoniales que son fruto de nuestro esfuerzo.<\/span><\/li><\/ol><\/li><\/ol><ol style=\"text-align: justify;\"><li style=\"list-style-type: none;\"><ol style=\"text-align: justify;\"><li style=\"text-align: justify;\"><span style=\"color: #4c4f54;\"><strong>La alta rentabilidad del il\u00edcito y la dificultad de atrapar a sus responsables<\/strong>. Los malhechores tienen gran ingenio para cometer sus fechor\u00edas y para conseguir enormes cantidades de dinero. Tan s\u00f3lo basta, por ejemplo, con robar los bolsillos o carteras para conseguir identificaciones personales, tarjetas bancarias\u2026 o con apoderarse de tu documentaci\u00f3n financiera.<\/span><\/li><\/ol><\/li><\/ol><ol style=\"text-align: justify;\"><li style=\"text-align: justify;\"><span style=\"color: #4c4f54;\"><strong>La socializaci\u00f3n del uso de Internet<\/strong> y el incremento de las transacciones electr\u00f3nicas.<\/span><\/li><\/ol><p><a href=\"http:\/\/tugesto.com\/software-lopd\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-20889 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/incorpora-un-delegado-proteccion-datos-informate.png\" alt=\"contrata-dpo\" width=\"800\" height=\"241\" srcset=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/incorpora-un-delegado-proteccion-datos-informate.png 800w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/incorpora-un-delegado-proteccion-datos-informate-300x90.png 300w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/incorpora-un-delegado-proteccion-datos-informate-768x231.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p><h2 style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">\u00bfC\u00f3mo prevenir la suplantaci\u00f3n de identidad?<\/span><\/h2><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Siguiendo el sabio refr\u00e1n <em>\u201cm\u00e1s vale prevenir que curar\u201d\u00a0<\/em>vamos a proporcionaros una serie de pautas o consejos para <strong>prevenir o evitar la suplantaci\u00f3n o robo de identidad<\/strong>.<\/span><\/p><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\"><strong>No compartas informaci\u00f3n personal ni financiera<\/strong>, es confidencial y debes manejarla con reservas. Proporcionar tus claves a amigos, tu pareja o familiares, para comprobar alguna transacci\u00f3n, puede ser un riesgo porque no sabes en qu\u00e9 equipo ingresar\u00e1n tus datos.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Aseg\u00farate que las p\u00e1ginas en que introduces tus datos tengan <strong>certificados de seguridad<\/strong>, el prefijo \u00abhttps:\/\/\u00bb que indica que est\u00e1n respaldadas y cuentan con candados para manejar tu informaci\u00f3n bancaria.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\"><strong>Revisa los estados de cuenta<\/strong> de tus instrumentos financieros, no dejes pasar ninguna irregularidad por m\u00e1s peque\u00f1a que sea.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\"><strong>Conserva los comprobantes digitales<\/strong> de los diferentes tipos de transacciones en l\u00ednea, generalmente cuando realizas una compra te llega una notificaci\u00f3n a tu correo.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">En caso de extrav\u00edo de tus documentos de identificaci\u00f3n, levanta una <strong>denuncia<\/strong> ante las autoridades.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\"><strong>No proporciones informaci\u00f3n<\/strong> comercial o personal en encuestas telef\u00f3nicas.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Ten cuidado en el manejo de documentos personales y financieros. Evita dejarlos al alcance de cualquiera, a\u00fan dentro de tu casa.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Ten <strong>especial cuidado<\/strong> con documentos que tengan tu <strong>firma personal y huella digital.<\/strong><\/span><\/li><li style=\"text-align: justify;\"><span style=\"color: #4c4f54;\"><strong>Ten cuidado cuando hagas compras en l\u00ednea.<\/strong> Siempre revisa los s\u00edmbolos de seguridad de la p\u00e1gina cuando compres en l\u00ednea. Adem\u00e1s, es mejor que tengas una <strong>tarjeta de cr\u00e9dito<\/strong> espec\u00edficamente para realizar compras en l\u00ednea. As\u00ed ser\u00e1 f\u00e1cil cancelarla si algo malo sucede y a\u00fan podr\u00e1s usar la tarjeta que utilizas \u201cen la vida real\u201d sin mayores problemas.\u00a0No guardes tu informaci\u00f3n en ninguna p\u00e1gina, incluso las de compras. Aunque te parezca conveniente, tienes mucho que perder si alguien hackea la p\u00e1gina. Evita utilizar tus <strong>medios de pago<\/strong> en lugares de dudosa reputaci\u00f3n o que no est\u00e9n debidamente establecidos.<\/span><\/li><\/ul><p style=\"text-align: justify;\"><a href=\"http:\/\/tugesto.com\/software-lopd\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-20888 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/Delegado-proteccion-datos-solicita-informacion.png\" alt=\"\" width=\"800\" height=\"241\" srcset=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/Delegado-proteccion-datos-solicita-informacion.png 800w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/Delegado-proteccion-datos-solicita-informacion-300x90.png 300w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2021\/09\/Delegado-proteccion-datos-solicita-informacion-768x231.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p><ul style=\"text-align: justify;\"><li><strong>Utiliza una buena contrase\u00f1a y PIN<\/strong>. Escoge palabras y n\u00fameros que nadie podr\u00eda adivinar, incluso si esa persona supiera tus otros <strong>datos perso<span style=\"color: #4c4f54;\">nales<\/span><\/strong><span style=\"color: #4c4f54;\">. Tambi\u00e9n puedes utilizar palabras o n\u00fameros que te sean conocidos, pero codif\u00edcalos de manera que sea dif\u00edcil descifrar tu contrase\u00f1a. O tira de <strong>mecanismos como el reconocimiento facial para desbloquear tus apps o m\u00f3vil<\/strong>. Usa m\u00e9todos como<\/span> <a href=\"http:\/\/es.wikihow.com\/codificar-y-decodificar-utilizando-la-cifra-de-Vigen%C3%A8re\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">el c\u00f3digo de Vigen\u00e8re<\/a>. <span style=\"color: #4c4f54;\">Incluso existen programas en l\u00ednea que generan contrase\u00f1as casi imposibles de descifrar o quebrar. Lo importante es que nunca uses una misma contrase\u00f1a. Adem\u00e1s, es una gran idea que empieces a tener los siguientes h\u00e1bitos:<\/span><br \/><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">No uses la misma contrase\u00f1a en todas tus cuentas. Var\u00eda tus contrase\u00f1as de cuenta a cuenta.<\/span><\/li><li><span style=\"color: #4c4f54;\">Evita tener un PIN que sea f\u00e1cil de adivinar, como fechas de nacimiento, secuencias num\u00e9ricas comunes, n\u00fameros de tel\u00e9fono, tu c\u00e9dula de identidad, etc.<\/span><\/li><li><span style=\"color: #4c4f54;\">Las mejores contrase\u00f1as contienen letras may\u00fasculas y min\u00fasculas, n\u00fameros y otros caracteres. Adem\u00e1s, contienen al menos 8 caracteres.<\/span><\/li><li><span style=\"color: #4c4f54;\">Nunca guardes tus contrase\u00f1as.<\/span><\/li><\/ul><\/li><li><span style=\"color: #4c4f54;\"><strong>Protege tu ordenador.<\/strong> Muchos criminales utilizan softwares muy avanzados, como un <strong>spyware o keylogger<\/strong> para obtener informaci\u00f3n personal, como las contrase\u00f1as y nombres del usuario sin el consentimiento del mismo. La mejor manera de evitar que uno de estos programas infecte tu ordenador es mantener actualizados tu firewall, antivirus y antispyware. Si no sabes qu\u00e9 es lo mejor para tu ordenador, llama a tu tienda de electr\u00f3nica para que te den consejos.<\/span><\/li><li><span style=\"color: #4c4f54;\"><strong>Evita introducir tu usuario y contrase\u00f1a en links extra\u00f1os <\/strong>que te lleguen por correo electr\u00f3nico. Para estafar a la gente, una persona env\u00eda correos electr\u00f3nicos aparentemente inocuos a la v\u00edctima haci\u00e9ndose pasar por una compa\u00f1\u00eda leg\u00edtima y le pide verificar informaci\u00f3n como sus contrase\u00f1as, n\u00fameros de cuenta y otros datos personales.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\"><strong>No des tus datos personales <\/strong>accidentalmente. Si vas a deshacerte de tu ordenador, aseg\u00farate de borrar toda tu informaci\u00f3n personal primero. As\u00ed, nadie podr\u00e1 hacerse pasar por ti o los tuyos.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Nunca respondas a<strong> correos electr\u00f3nicos no deseados.<\/strong><\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Presta atenci\u00f3n por si alguien mira por encima de tu hombro mientras<strong> realizas transacciones.<\/strong><\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Cambia la <strong>configuraci\u00f3n de tus tarjetas de cr\u00e9dito<\/strong> para que necesites el PIN en cualquier transacci\u00f3n.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Coloca tu<strong> cartera y tu billetera<\/strong> en un lugar seguro<strong>.<\/strong><\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Deja en casa la <strong>tarjeta de la seguridad social<\/strong> y las tarjetas de cr\u00e9dito que no necesites.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\"><strong>Destruye cualquier documento que tenga tu informaci\u00f3n personal escrita.<\/strong> No tires tus facturas viejas y otros documentos similares en la basura.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\">Aseg\u00farate de <strong>triturar las ofertas de cr\u00e9dito<\/strong> pre aprobadas que te lleguen (por ejemplo, si te env\u00edan tarjeta de cr\u00e9dito).<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\"><strong>Protege tu correo postal<\/strong>.<\/span><\/li><\/ul><ul style=\"text-align: justify;\"><li><span style=\"color: #4c4f54;\"><strong>Protege tus facturas de tel\u00e9fono<\/strong>. En ellas normalmente aparecen todos los datos personales (nombre, NIF, direcci\u00f3n, tel\u00e9fonos, banco, terminaci\u00f3n de cuenta bancaria). Ten en cuenta que con estos datos alguna persona podr\u00eda solicitar alta de una nueva l\u00ednea telef\u00f3nica y conseguir terminales m\u00f3viles a tu nombre.<\/span><\/li><\/ul><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Intenta aplicar siempre estos consejos pensando en el precio o valor de tus datos personales y evita, as\u00ed, cualquier tipo de suplantaci\u00f3n de identidad y da\u00f1os derivados de la misma.<\/span><\/p><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">\u00bfY a ti? \u00bfTe han suplantado alguna vez la identidad?<\/span><\/p><p style=\"text-align: justify;\"><span style=\"color: #4c4f54;\">Si necesitas asesoramiento en protecci\u00f3n de datos <a href=\"http:\/\/www.tugesto.com\/contacto\" target=\"_blank\" rel=\"noopener\">contacta con nosotros<\/a>.<\/span><\/p><p style=\"text-align: justify;\"><a href=\"https:\/\/tugesto.com\/software-lopd\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2752 size-full\" title=\"Soluci\u00f3n INPD. Instituto Nacional de Protecci\u00f3n de Datos.\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/CTA-inpd.jpg\" alt=\"Solicita m\u00e1s informaci\u00f3n sobre la soluci\u00f3n online para la protecci\u00f3n de datos en tu empresa.\" width=\"680\" height=\"270\" srcset=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/CTA-inpd.jpg 680w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/CTA-inpd-300x119.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/a><\/p><p style=\"text-align: justify;\"><em><span style=\"color: #4c4f54;\">Laura Carrillo,\u00a0Auditora LOPD\u00a0de tugesto<\/span><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La protecci\u00f3n de los\u00a0datos personales cobra una\u00a0importancia especial en el mundo actual donde vivimos. La inevitable revoluci\u00f3n tecnol\u00f3gica ha modificado nuestro modus vivendi, manifestando un uso diario de Internet en diferentes dispositivos: m\u00f3vil, ordenador, tablet\u2026 Muy cerca del uso de la\u00a0tecnolog\u00eda se encuentra el sujeto que se aprovecha de la vulnerabilidad de la v\u00edctima, y [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_eb_attr":"","content-type":"","footnotes":""},"categories":[51],"tags":[36,1306,38],"ppma_author":[1500],"class_list":["post-2741","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-proteccion-de-datos","tag-autonomos","tag-legal","tag-pymes","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo evitar la suplantaci\u00f3n de identidad | tugesto<\/title>\n<meta name=\"description\" content=\"Te contamos c\u00f3mo evitar la suplantaci\u00f3n de identidad y c\u00f3mo luchar contra ella. \u00a1Protege tus datos personales con nuestros consejos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo evitar la suplantaci\u00f3n de identidad | tugesto\" \/>\n<meta property=\"og:description\" content=\"Te contamos c\u00f3mo evitar la suplantaci\u00f3n de identidad y c\u00f3mo luchar contra ella. \u00a1Protege tus datos personales con nuestros consejos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog: \u00a1Aprende a emprender! | tugesto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tugesto\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-05T11:59:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T09:55:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/suplantacion-identidad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carmen Carbonell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carmen Carbonell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/\"},\"author\":{\"name\":\"Carmen Carbonell\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/person\\\/bf3b1b7501a0b5ae2bb78ceffd7970ab\"},\"headline\":\"C\u00f3mo evitar la suplantaci\u00f3n de identidad\",\"datePublished\":\"2016-04-05T11:59:25+00:00\",\"dateModified\":\"2024-05-21T09:55:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/\"},\"wordCount\":1476,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/suplantacion-identidad.jpg\",\"keywords\":[\"aut\u00f3nomos\",\"legal\",\"pymes\"],\"articleSection\":[\"Protecci\u00f3n de datos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/\",\"name\":\"C\u00f3mo evitar la suplantaci\u00f3n de identidad | tugesto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/suplantacion-identidad.jpg\",\"datePublished\":\"2016-04-05T11:59:25+00:00\",\"dateModified\":\"2024-05-21T09:55:21+00:00\",\"description\":\"Te contamos c\u00f3mo evitar la suplantaci\u00f3n de identidad y c\u00f3mo luchar contra ella. \u00a1Protege tus datos personales con nuestros consejos!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/suplantacion-identidad.jpg\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/suplantacion-identidad.jpg\",\"width\":700,\"height\":329,\"caption\":\"C\u00f3mo evitar la suplantaci\u00f3n de identidad y c\u00f3mo luchar contra ella en una contrataci\u00f3n irregular de servicios de telecomunicaciones.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/evitar-suplantacion-de-identidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protecci\u00f3n de datos\",\"item\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/category\\\/proteccion-de-datos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo evitar la suplantaci\u00f3n de identidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\",\"name\":\"Blog tugesto\",\"description\":\"\ud83d\udcda Blog especializado para aut\u00f3nomos y pymes. Encuentra semanalmente nuevos posts, recursos y gu\u00edas. La ayuda que necesitas para tu negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\",\"name\":\"tugesto\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo_tugesto.png\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo_tugesto.png\",\"width\":190,\"height\":63,\"caption\":\"tugesto\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tugesto\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tugesto_online\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/person\\\/bf3b1b7501a0b5ae2bb78ceffd7970ab\",\"name\":\"Carmen Carbonell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/carmen-carbonell.jpg8373b5b7224f83881cfd2ee12b6ab7b2\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/carmen-carbonell.jpg\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/carmen-carbonell.jpg\",\"caption\":\"Carmen Carbonell\"},\"description\":\"Maquetaci\u00f3n y programaci\u00f3n back-end y front-end\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo evitar la suplantaci\u00f3n de identidad | tugesto","description":"Te contamos c\u00f3mo evitar la suplantaci\u00f3n de identidad y c\u00f3mo luchar contra ella. \u00a1Protege tus datos personales con nuestros consejos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo evitar la suplantaci\u00f3n de identidad | tugesto","og_description":"Te contamos c\u00f3mo evitar la suplantaci\u00f3n de identidad y c\u00f3mo luchar contra ella. \u00a1Protege tus datos personales con nuestros consejos!","og_url":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/","og_site_name":"Blog: \u00a1Aprende a emprender! | tugesto","article_publisher":"https:\/\/www.facebook.com\/tugesto\/","article_published_time":"2016-04-05T11:59:25+00:00","article_modified_time":"2024-05-21T09:55:21+00:00","og_image":[{"width":700,"height":329,"url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/suplantacion-identidad.jpg","type":"image\/jpeg"}],"author":"Carmen Carbonell","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carmen Carbonell","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/#article","isPartOf":{"@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/"},"author":{"name":"Carmen Carbonell","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/person\/bf3b1b7501a0b5ae2bb78ceffd7970ab"},"headline":"C\u00f3mo evitar la suplantaci\u00f3n de identidad","datePublished":"2016-04-05T11:59:25+00:00","dateModified":"2024-05-21T09:55:21+00:00","mainEntityOfPage":{"@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/"},"wordCount":1476,"commentCount":0,"publisher":{"@id":"https:\/\/tugesto.com\/blog\/#organization"},"image":{"@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/#primaryimage"},"thumbnailUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/suplantacion-identidad.jpg","keywords":["aut\u00f3nomos","legal","pymes"],"articleSection":["Protecci\u00f3n de datos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/","url":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/","name":"C\u00f3mo evitar la suplantaci\u00f3n de identidad | tugesto","isPartOf":{"@id":"https:\/\/tugesto.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/#primaryimage"},"image":{"@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/#primaryimage"},"thumbnailUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/suplantacion-identidad.jpg","datePublished":"2016-04-05T11:59:25+00:00","dateModified":"2024-05-21T09:55:21+00:00","description":"Te contamos c\u00f3mo evitar la suplantaci\u00f3n de identidad y c\u00f3mo luchar contra ella. \u00a1Protege tus datos personales con nuestros consejos!","breadcrumb":{"@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/#primaryimage","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/suplantacion-identidad.jpg","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2014\/12\/suplantacion-identidad.jpg","width":700,"height":329,"caption":"C\u00f3mo evitar la suplantaci\u00f3n de identidad y c\u00f3mo luchar contra ella en una contrataci\u00f3n irregular de servicios de telecomunicaciones."},{"@type":"BreadcrumbList","@id":"https:\/\/tugesto.com\/blog\/evitar-suplantacion-de-identidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tugesto.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Protecci\u00f3n de datos","item":"https:\/\/tugesto.com\/blog\/category\/proteccion-de-datos\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo evitar la suplantaci\u00f3n de identidad"}]},{"@type":"WebSite","@id":"https:\/\/tugesto.com\/blog\/#website","url":"https:\/\/tugesto.com\/blog\/","name":"Blog tugesto","description":"\ud83d\udcda Blog especializado para aut\u00f3nomos y pymes. Encuentra semanalmente nuevos posts, recursos y gu\u00edas. La ayuda que necesitas para tu negocio.","publisher":{"@id":"https:\/\/tugesto.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tugesto.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tugesto.com\/blog\/#organization","name":"tugesto","url":"https:\/\/tugesto.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2019\/06\/logo_tugesto.png","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2019\/06\/logo_tugesto.png","width":190,"height":63,"caption":"tugesto"},"image":{"@id":"https:\/\/tugesto.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tugesto\/","https:\/\/www.instagram.com\/tugesto_online\/"]},{"@type":"Person","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/person\/bf3b1b7501a0b5ae2bb78ceffd7970ab","name":"Carmen Carbonell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg8373b5b7224f83881cfd2ee12b6ab7b2","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg","caption":"Carmen Carbonell"},"description":"Maquetaci\u00f3n y programaci\u00f3n back-end y front-end"}]}},"authors":[{"term_id":1500,"user_id":14,"is_guest":0,"slug":"carmen-carbonell","display_name":"Carmen Carbonell","avatar_url":{"url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg","url2x":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/2741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/comments?post=2741"}],"version-history":[{"count":11,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/2741\/revisions"}],"predecessor-version":[{"id":37201,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/2741\/revisions\/37201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/media\/4918"}],"wp:attachment":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/media?parent=2741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/categories?post=2741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/tags?post=2741"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/ppma_author?post=2741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}