{"id":1487,"date":"2015-11-23T16:52:40","date_gmt":"2015-11-23T15:52:40","guid":{"rendered":"http:\/\/tugesto.com\/blog\/?p=1487"},"modified":"2024-05-21T12:14:22","modified_gmt":"2024-05-21T10:14:22","slug":"suplantacion-identidad-internet","status":"publish","type":"post","link":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/","title":{"rendered":"Suplantaci\u00f3n de identidad en Internet: todo lo que debes saber"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1487\" class=\"elementor elementor-1487\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46e14983 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46e14983\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-438c5ea3\" data-id=\"438c5ea3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-271ec846 elementor-widget elementor-widget-text-editor\" data-id=\"271ec846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">En la actualidad, pr\u00e1cticamente todo el mundo tiene presencia en Internet. Si buscas tu nombre en Google es posible que te sorprendas de la cantidad de sitios web donde puedes aparecer. Por eso, al mismo tiempo que sucede lo anterior <strong>cada vez son m\u00e1s los casos de suplantaci\u00f3n de identidad en Internet<\/strong>.<\/p><p style=\"text-align: justify;\">Se tiene entendido que cada uno puede gestionar su privacidad en Internet, pero no siempre se puede estar totalmente seguro de las consecuencias que pueda acarrear el crear un perfil en una red social, dar informaci\u00f3n personal de tu vida o subir una fotograf\u00eda personal.<\/p><p style=\"text-align: justify;\">Son muchas las personas que <strong>se aprovechan de estas circunstancias para usurpar la identidad con fines denunciables<\/strong>. En este post vamos a hablaros de c\u00f3mo la suplantaci\u00f3n de identidad en Internet es un delito y <strong>c\u00f3mo actuar si te ves envuelto en un caso as\u00ed<\/strong>.<\/p><p><a href=\"http:\/\/tugesto.com\/asesoria-legal\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-14909 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoramiento-48h-consultas-legales-tugesto.jpg\" alt=\"En menos de 48 horas un abogado de tugesto estudiar\u00e1 tu caso\" width=\"1216\" height=\"367\" srcset=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoramiento-48h-consultas-legales-tugesto.jpg 1216w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoramiento-48h-consultas-legales-tugesto-300x91.jpg 300w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoramiento-48h-consultas-legales-tugesto-1024x309.jpg 1024w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoramiento-48h-consultas-legales-tugesto-768x232.jpg 768w\" sizes=\"(max-width: 1216px) 100vw, 1216px\" \/><\/a><\/p><h2 style=\"text-align: justify;\">\u00bfQu\u00e9 se entiende por suplantaci\u00f3n de identidad en Internet?<\/h2><p style=\"text-align: justify;\">La suplantaci\u00f3n de identidad digital, llamado tambi\u00e9n <em>Phishing<\/em>, es la <strong>acci\u00f3n por la que un individuo se hace pasar por otra persona para realizar actividades ilegales<\/strong> para beneficio propio. Es uno de <strong><a href=\"https:\/\/tugesto.com\/blog\/los-delitos-mas-frecuentes-en-internet\/\" target=\"_blank\" rel=\"noopener\">los delitos m\u00e1s frecuentes en Internet<\/a><\/strong> por la poca seguridad que presenta varias p\u00e1ginas webs, redes sociales o aplicaciones.<\/p><p style=\"text-align: justify;\">En Internet <strong>la finalidad de estos actos var\u00eda dependiendo de cada caso<\/strong>, puede ser desde comprar online con la tarjeta de cr\u00e9dito de la v\u00edctima, contratar servicios o atacar la integridad f\u00edsica y moral de la persona suplantada.<\/p><p style=\"text-align: justify;\">Cada vez estos actos son m\u00e1s habituales en Internet, sobre todo en las redes sociales, escenario donde se producen m\u00e1s actos delictivos de suplantaci\u00f3n de identidad. En ellas, el usurpador se sirve de estas plataformas para <strong>insultar a terceras personas<\/strong> o incluso para apropiarse de informaci\u00f3n relevante de las v\u00edctimas para <strong>cometer fraudes o realizar ciberacoso<\/strong>.<\/p><h2 style=\"text-align: justify;\">\u00bfCu\u00e1ndo se considera delito suplantar la identidad de una persona?<\/h2><p style=\"text-align: justify;\">No siempre se considera delito la suplantaci\u00f3n de identidad, y <strong>la pena var\u00eda dependiendo de cada caso<\/strong>. Por ejemplo, no es denunciable usar \u00fanicamente el nombre de la persona, es decir, \u00a0si un usuario registra un perfil en un foro utilizando s\u00f3lo el nombre (sin aportar m\u00e1s datos relevantes o fotograf\u00edas) y participa en un debate de opini\u00f3n en Internet no se considera delito.<\/p><p style=\"text-align: justify;\">Si por otro lado, <strong>el individuo crea un perfil falso y hace uso de una imagen o informaci\u00f3n relevante de otra persona,<\/strong> est\u00e1 cometiendo un <strong>delito de vulneraci\u00f3n del derecho a la propia imagen<\/strong> tipificado en el <a href=\"http:\/\/www.congreso.es\/consti\/constitucion\/indice\/titulos\/articulos.jsp?ini=18&amp;tipo=2\" target=\"_blank\" rel=\"noopener noreferrer\">art\u00edculo 18 de la Constituci\u00f3n<\/a> y pudiendo ser penado con c\u00e1rcel hasta 3 a\u00f1os tal y como indica el art\u00edculo 401 del C\u00f3digo Penal.<\/p><p style=\"text-align: justify;\">Otro caso delictivo en lo que se refiere a la suplantaci\u00f3n de identidad es cuando un <strong>usuario accede al perfil de otra persona sin su consentimiento<\/strong>. Del mismo modo que en el caso anterior, se est\u00e1 infringiendo la ley ya que se comete un <strong>delito de lesi\u00f3n de privacidad<\/strong>, recogido en el art\u00edculo 197 del C\u00f3digo Penal en el cap\u00edtulo I <em>Del descubrimiento y revelaci\u00f3n de secretos<\/em>. Por otro lado, el usuario que para acceder al perfil haya <strong>robado contrase\u00f1as o cuentas<\/strong> estar\u00e1 cometiendo tambi\u00e9n el delito de <strong>da\u00f1os a redes<\/strong>, soportes o sistemas inform\u00e1ticos tipificado en el art\u00edculo 264 del C\u00f3digo Penal.<\/p><p>Te puede interesar: <a href=\"https:\/\/www.aepd.es\/\" target=\"_blank\" rel=\"noopener\"><em>Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (AEPD)<\/em><\/a><\/p><p style=\"text-align: justify;\"><a href=\"http:\/\/tugesto.com\/software-lopd\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-7899 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2018\/01\/LOPD.gif\" alt=\"Servicio de protecci\u00f3n de datos\" width=\"1000\" height=\"600\" \/><\/a><\/p><h2 style=\"text-align: justify;\">\u00bfC\u00f3mo puedo saber si han suplantado mi identidad en Internet?<\/h2><p style=\"text-align: justify;\">En muchos casos, gracias a terceras personas o incluso a las propias redes y plataformas que te avisan de una conexi\u00f3n inusual a tu cuenta, puedes enterarte que alguien se est\u00e1 pasando por ti en una red social, correo electr\u00f3nico, etc.<\/p><p style=\"text-align: justify;\">No obstante <strong>algunas veces la usurpaci\u00f3n de identidad no es tan evidente<\/strong> y debes atender varios aspectos importantes para saber si han accedido a tu cuenta personal.<\/p><p style=\"text-align: justify;\">A continuaci\u00f3n te mostramos una lista que puede evidenciar la suplantaci\u00f3n de tu identidad en Internet:<\/p><ul style=\"text-align: justify;\"><li><strong>No encuentro mensajes privados o emails<\/strong> en mi cuenta<\/li><li>He descubierto una <strong>publicaci\u00f3n o un comentario que yo no he realizado<\/strong><\/li><li>Me encuentro con <strong>conversaciones de chats que no recuerdo<\/strong> haber mantenido<\/li><li><strong>Mi lista de contactos ha crecido o se ha eliminado<\/strong> un seguidor sin saberlo<\/li><li>Recibo en mi correo electr\u00f3nico <strong>emails que me indica que se ha intentado recuperar o modificar la contrase\u00f1a<\/strong> de alguna de mis cuentas<\/li><\/ul><h2 style=\"text-align: justify;\">\u00bfQu\u00e9 debo hacer si soy v\u00edctima de una suplantaci\u00f3n de identidad en Internet?<\/h2><h3 style=\"text-align: justify;\">D\u00e9jate asesorar por abogados especializados<\/h3><p style=\"text-align: justify;\">Si han suplantado tu identidad y no tienes ni idea de c\u00f3mo afrontar la situaci\u00f3n, lo mejor que puedes hacer es dejarte asesorar por <strong>abogados especializados en <a href=\"http:\/\/www.tugesto.com\/software-lopd\" target=\"_blank\" rel=\"noopener\">Protecci\u00f3n de Datos<\/a><\/strong>. De ese modo, aunque sigas por tu cuenta los siguientes pasos que te planteamos a continuaci\u00f3n, podr\u00e1s hacer frente a cualquier imprevisto que se interponga en tu camino indicando qu\u00e9 medidas tomar.<\/p><h3 style=\"text-align: justify;\">Recopila pruebas que puedan servirte para denunciar<\/h3><p style=\"text-align: justify;\">Uno de los primeros pasos que tienes que hacer es <strong>guardar, capturar y revisar con total atenci\u00f3n cualquier acto delictivo o sospechoso en alguna de tus cuentas<\/strong>. Esta informaci\u00f3n es relevante a la hora de denunciar al culpable.<\/p><h3 style=\"text-align: justify;\">Cambia tu contrase\u00f1a inmediatamente<\/h3><p style=\"text-align: justify;\">En el caso que hayan accedido a tu cuenta\u00a0 despu\u00e9s de haberte robado la contrase\u00f1a lo primero que tienes que hacer es cambiarla para <strong>evitar que vuelvan a acceder sin tu permiso<\/strong>. Te sugerimos en ese caso que <strong>escojas una contrase\u00f1a compleja<\/strong> o como m\u00ednimo cumpla los requisitos de la plataforma.<\/p><p style=\"text-align: justify;\">Si esa contrase\u00f1a es utilizada en otras plataformas te aconsejamos modificarla en todas las p\u00e1ginas web.<\/p><p style=\"text-align: justify;\">Debes atender tambi\u00e9n a la seguridad de tu ordenador, tablet o m\u00f3vil desde donde accedes a Internet. <strong>Actualiza el antivirus<\/strong> para evitar un posible intrusismo a tus cuentas.<\/p><h3 style=\"text-align: justify;\">Haz tu denuncia en la red social o plataforma para que retiren la cuenta<\/h3><p style=\"text-align: justify;\">En el caso de que hayan creado una cuenta falsa con informaci\u00f3n relevante hacia tu persona o hayan utilizado fotos tuyas personales, lo primero que debes hacer es <strong>realizar una denuncia directamente a la plataforma o red social<\/strong>.<\/p><p style=\"text-align: justify;\">A continuaci\u00f3n te dejamos los enlaces para que puedas a acceder a denunciar una cuenta ilegal:<\/p><ul style=\"text-align: justify;\"><li><a href=\"https:\/\/www.facebook.com\/help\/www\/263149623790594\/\" target=\"_blank\" rel=\"noopener noreferrer\">C\u00f3mo denunciar en Facebook<\/a><\/li><li><a href=\"https:\/\/support.twitter.com\/articles\/20170183\" target=\"_blank\" rel=\"noopener noreferrer\">C\u00f3mo denunciar en Twitter<\/a><\/li><li><a href=\"https:\/\/ayuda.linkedin.com\/app\/answers\/detail\/a_id\/30432\/related\/1\" target=\"_blank\" rel=\"noopener noreferrer\">C\u00f3mo denunciar en LinkedIn<\/a><\/li><li><a href=\"https:\/\/help.instagram.com\/446663175382270\/\" target=\"_blank\" rel=\"noopener noreferrer\">C\u00f3mo denunciar en Instagram<\/a><\/li><\/ul><h3 style=\"text-align: justify;\">Acude a las Fuerzas y Cuerpos de Seguridad del Estado para denunciar en el caso de que sea necesario<\/h3><p style=\"text-align: justify;\">Si tras denunciar los hechos a la red social el problema\u00a0 no se ha resuelto, dir\u00edgete al <a href=\"https:\/\/denuncias.policia.es\/OVD\/\" target=\"_blank\" rel=\"noopener\">Cuerpo Nacional de Polic\u00eda<\/a> o al <a href=\"https:\/\/www.gdt.guardiacivil.es\/webgdt\/home_alerta.php\" target=\"_blank\" rel=\"noopener\">grupo de delitos telem\u00e1ticos de la Guardia Civil<\/a> para efectuar tu denuncia contra la persona culpable.<\/p><p><a href=\"http:\/\/tugesto.com\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-14765 size-full\" src=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoria_online_tugesto.jpg\" alt=\"Ahorra tiempo y dinero con nuestra gesti\u00f3n online\" width=\"800\" height=\"241\" srcset=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoria_online_tugesto.jpg 800w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoria_online_tugesto-300x90.jpg 300w, https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2020\/01\/asesoria_online_tugesto-768x231.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p><p style=\"text-align: justify;\">\u00bfY t\u00fa? \u00bfHas sufrido alguna vez la suplantaci\u00f3n o robo de tu identidad en Internet? \u00bfC\u00f3mo actuaste en ese caso?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En la actualidad, pr\u00e1cticamente todo el mundo tiene presencia en Internet. Si buscas tu nombre en Google es posible que te sorprendas de la cantidad de sitios web donde puedes aparecer. Por eso, al mismo tiempo que sucede lo anterior cada vez son m\u00e1s los casos de suplantaci\u00f3n de identidad en Internet. Se tiene entendido [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":1490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_eb_attr":"","content-type":"","footnotes":""},"categories":[51],"tags":[36,1306,38],"ppma_author":[1500],"class_list":["post-1487","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-proteccion-de-datos","tag-autonomos","tag-legal","tag-pymes","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suplantaci\u00f3n de identidad en internet | tugesto<\/title>\n<meta name=\"description\" content=\"Conoce en qu\u00e9 consiste la suplantaci\u00f3n de identidad en Internet y c\u00f3mo actuar frente a un acto delictivo en tus cuentas personales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suplantaci\u00f3n de identidad en internet | tugesto\" \/>\n<meta property=\"og:description\" content=\"Conoce en qu\u00e9 consiste la suplantaci\u00f3n de identidad en Internet y c\u00f3mo actuar frente a un acto delictivo en tus cuentas personales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog: \u00a1Aprende a emprender! | tugesto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tugesto\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-23T15:52:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T10:14:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/11\/suplantacion-identidad-internet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carmen Carbonell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carmen Carbonell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/\"},\"author\":{\"name\":\"Carmen Carbonell\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/person\\\/bf3b1b7501a0b5ae2bb78ceffd7970ab\"},\"headline\":\"Suplantaci\u00f3n de identidad en Internet: todo lo que debes saber\",\"datePublished\":\"2015-11-23T15:52:40+00:00\",\"dateModified\":\"2024-05-21T10:14:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/\"},\"wordCount\":1190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/suplantacion-identidad-internet.jpg\",\"keywords\":[\"aut\u00f3nomos\",\"legal\",\"pymes\"],\"articleSection\":[\"Protecci\u00f3n de datos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/\",\"name\":\"Suplantaci\u00f3n de identidad en internet | tugesto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/suplantacion-identidad-internet.jpg\",\"datePublished\":\"2015-11-23T15:52:40+00:00\",\"dateModified\":\"2024-05-21T10:14:22+00:00\",\"description\":\"Conoce en qu\u00e9 consiste la suplantaci\u00f3n de identidad en Internet y c\u00f3mo actuar frente a un acto delictivo en tus cuentas personales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/suplantacion-identidad-internet.jpg\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/suplantacion-identidad-internet.jpg\",\"width\":700,\"height\":329,\"caption\":\"La suplantaci\u00f3n de identidad es un acto totalmente ilegal, por lo que si lo sufres o has sufrido que sepas c\u00f3mo hacer frente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/suplantacion-identidad-internet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protecci\u00f3n de datos\",\"item\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/category\\\/proteccion-de-datos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Suplantaci\u00f3n de identidad en Internet: todo lo que debes saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\",\"name\":\"Blog tugesto\",\"description\":\"\ud83d\udcda Blog especializado para aut\u00f3nomos y pymes. Encuentra semanalmente nuevos posts, recursos y gu\u00edas. La ayuda que necesitas para tu negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#organization\",\"name\":\"tugesto\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo_tugesto.png\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo_tugesto.png\",\"width\":190,\"height\":63,\"caption\":\"tugesto\"},\"image\":{\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tugesto\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tugesto_online\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/#\\\/schema\\\/person\\\/bf3b1b7501a0b5ae2bb78ceffd7970ab\",\"name\":\"Carmen Carbonell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/carmen-carbonell.jpg8373b5b7224f83881cfd2ee12b6ab7b2\",\"url\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/carmen-carbonell.jpg\",\"contentUrl\":\"https:\\\/\\\/tugesto.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/carmen-carbonell.jpg\",\"caption\":\"Carmen Carbonell\"},\"description\":\"Maquetaci\u00f3n y programaci\u00f3n back-end y front-end\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suplantaci\u00f3n de identidad en internet | tugesto","description":"Conoce en qu\u00e9 consiste la suplantaci\u00f3n de identidad en Internet y c\u00f3mo actuar frente a un acto delictivo en tus cuentas personales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/","og_locale":"es_ES","og_type":"article","og_title":"Suplantaci\u00f3n de identidad en internet | tugesto","og_description":"Conoce en qu\u00e9 consiste la suplantaci\u00f3n de identidad en Internet y c\u00f3mo actuar frente a un acto delictivo en tus cuentas personales","og_url":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/","og_site_name":"Blog: \u00a1Aprende a emprender! | tugesto","article_publisher":"https:\/\/www.facebook.com\/tugesto\/","article_published_time":"2015-11-23T15:52:40+00:00","article_modified_time":"2024-05-21T10:14:22+00:00","og_image":[{"width":700,"height":329,"url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/11\/suplantacion-identidad-internet.jpg","type":"image\/jpeg"}],"author":"Carmen Carbonell","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carmen Carbonell","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/#article","isPartOf":{"@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/"},"author":{"name":"Carmen Carbonell","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/person\/bf3b1b7501a0b5ae2bb78ceffd7970ab"},"headline":"Suplantaci\u00f3n de identidad en Internet: todo lo que debes saber","datePublished":"2015-11-23T15:52:40+00:00","dateModified":"2024-05-21T10:14:22+00:00","mainEntityOfPage":{"@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/"},"wordCount":1190,"commentCount":0,"publisher":{"@id":"https:\/\/tugesto.com\/blog\/#organization"},"image":{"@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/#primaryimage"},"thumbnailUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/11\/suplantacion-identidad-internet.jpg","keywords":["aut\u00f3nomos","legal","pymes"],"articleSection":["Protecci\u00f3n de datos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/","url":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/","name":"Suplantaci\u00f3n de identidad en internet | tugesto","isPartOf":{"@id":"https:\/\/tugesto.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/#primaryimage"},"image":{"@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/#primaryimage"},"thumbnailUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/11\/suplantacion-identidad-internet.jpg","datePublished":"2015-11-23T15:52:40+00:00","dateModified":"2024-05-21T10:14:22+00:00","description":"Conoce en qu\u00e9 consiste la suplantaci\u00f3n de identidad en Internet y c\u00f3mo actuar frente a un acto delictivo en tus cuentas personales","breadcrumb":{"@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/#primaryimage","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/11\/suplantacion-identidad-internet.jpg","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2015\/11\/suplantacion-identidad-internet.jpg","width":700,"height":329,"caption":"La suplantaci\u00f3n de identidad es un acto totalmente ilegal, por lo que si lo sufres o has sufrido que sepas c\u00f3mo hacer frente"},{"@type":"BreadcrumbList","@id":"https:\/\/tugesto.com\/blog\/suplantacion-identidad-internet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tugesto.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Protecci\u00f3n de datos","item":"https:\/\/tugesto.com\/blog\/category\/proteccion-de-datos\/"},{"@type":"ListItem","position":3,"name":"Suplantaci\u00f3n de identidad en Internet: todo lo que debes saber"}]},{"@type":"WebSite","@id":"https:\/\/tugesto.com\/blog\/#website","url":"https:\/\/tugesto.com\/blog\/","name":"Blog tugesto","description":"\ud83d\udcda Blog especializado para aut\u00f3nomos y pymes. Encuentra semanalmente nuevos posts, recursos y gu\u00edas. La ayuda que necesitas para tu negocio.","publisher":{"@id":"https:\/\/tugesto.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tugesto.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tugesto.com\/blog\/#organization","name":"tugesto","url":"https:\/\/tugesto.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2019\/06\/logo_tugesto.png","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2019\/06\/logo_tugesto.png","width":190,"height":63,"caption":"tugesto"},"image":{"@id":"https:\/\/tugesto.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tugesto\/","https:\/\/www.instagram.com\/tugesto_online\/"]},{"@type":"Person","@id":"https:\/\/tugesto.com\/blog\/#\/schema\/person\/bf3b1b7501a0b5ae2bb78ceffd7970ab","name":"Carmen Carbonell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg8373b5b7224f83881cfd2ee12b6ab7b2","url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg","contentUrl":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg","caption":"Carmen Carbonell"},"description":"Maquetaci\u00f3n y programaci\u00f3n back-end y front-end"}]}},"authors":[{"term_id":1500,"user_id":14,"is_guest":0,"slug":"carmen-carbonell","display_name":"Carmen Carbonell","avatar_url":{"url":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg","url2x":"https:\/\/tugesto.com\/blog\/wp-content\/uploads\/2024\/05\/carmen-carbonell.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/1487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/comments?post=1487"}],"version-history":[{"count":17,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/1487\/revisions"}],"predecessor-version":[{"id":37143,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/posts\/1487\/revisions\/37143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/media\/1490"}],"wp:attachment":[{"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/media?parent=1487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/categories?post=1487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/tags?post=1487"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/tugesto.com\/blog\/wp-json\/wp\/v2\/ppma_author?post=1487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}